{"id":7394,"date":"2023-12-18T15:27:55","date_gmt":"2023-12-18T20:27:55","guid":{"rendered":"http:\/\/52.205.55.161\/?page_id=7394"},"modified":"2026-04-22T16:51:31","modified_gmt":"2026-04-22T21:51:31","slug":"opportunites","status":"publish","type":"page","link":"https:\/\/indicatic.org.pa\/fr\/oportunidades\/","title":{"rendered":"Opportunit\u00e9s"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"7394\" class=\"elementor elementor-7394\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6077b577 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6077b577\" data-element_type=\"section\" data-e-type=\"section\" id=\"vacantes\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-122258c8\" data-id=\"122258c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65912508 elementor-position-above elementor-widget__width-inherit elementor-tablet-position-left elementor-widget-tablet__width-inherit elementor-widget elementor-widget-heading\" data-id=\"65912508\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-wrapper\" ><div class=\"elementor-heading-wrapper-inner\"><h2 class=\"elementor-heading-title elementor-size-default\">Postes vacants<\/h2><span class=\"sub-title\">Opportunit\u00e9s<\/span><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1556dad elementor-grid-eael-col-4 elementor-grid-tablet-eael-col-2 elementor-grid-mobile-eael-col-1 elementor-widget elementor-widget-eael-post-grid\" data-id=\"1556dad\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;eael_post_grid_columns&quot;:&quot;eael-col-4&quot;,&quot;eael_post_grid_columns_tablet&quot;:&quot;eael-col-2&quot;,&quot;eael_post_grid_columns_mobile&quot;:&quot;eael-col-1&quot;}\" data-widget_type=\"eael-post-grid.default\">\n\t\t\t\t\t<div id=\"eael-post-grid-1556dad\" class=\"eael-post-grid-container\">\n            <div class=\"eael-post-grid eael-post-appender eael-post-appender-1556dad eael-post-grid-style-one\" data-layout-mode=\"masonry\"><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-10597\" data-id=\"10597\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/indicatic.org.pa\/fr\/oportunidades\/vacante-asistente-tecnico-en-tecnologia-indicatic-aip\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/08\/Vacante_agosto2026-1080x1080-X-LK-3-600x600.png\" class=\"attachment-medium size-medium wp-image-10608\" alt=\"Vacante Asistente de Proyecto de Investigaci\u00f3n Panam\u00e1\" srcset=\"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/08\/Vacante_agosto2026-1080x1080-X-LK-3-600x600.png 600w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/08\/Vacante_agosto2026-1080x1080-X-LK-3-1024x1024.png 1024w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/08\/Vacante_agosto2026-1080x1080-X-LK-3-150x150.png 150w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/08\/Vacante_agosto2026-1080x1080-X-LK-3-768x768.png 768w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/08\/Vacante_agosto2026-1080x1080-X-LK-3-12x12.png 12w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/08\/Vacante_agosto2026-1080x1080-X-LK-3-700x700.png 700w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/08\/Vacante_agosto2026-1080x1080-X-LK-3-100x100.png 100w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/08\/Vacante_agosto2026-1080x1080-X-LK-3.png 1080w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/indicatic.org.pa\/fr\/oportunidades\/vacante-asistente-tecnico-en-tecnologia-indicatic-aip\/\" title=\"Vacante: Asistente de Proyecto de Investigaci\u00f3n | INDICATIC AIP\">Vacante: Asistente de Proyecto de Investigaci\u00f3n | INDICATIC AIP<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Poste vacant<\/p><\/div>\n                    <\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-8916\" data-id=\"8916\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/indicatic.org.pa\/fr\/oportunidades\/vacante-asistente-investigacion-ingenieria-panama-junio-2025\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/if-feed-y-web-600x600.jpg\" class=\"attachment-medium size-medium wp-image-10442\" alt=\"if feed y web\" srcset=\"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/if-feed-y-web-600x600.jpg 600w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/if-feed-y-web-1024x1024.jpg 1024w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/if-feed-y-web-150x150.jpg 150w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/if-feed-y-web-768x768.jpg 768w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/if-feed-y-web-12x12.jpg 12w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/if-feed-y-web-700x700.jpg 700w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/if-feed-y-web-100x100.jpg 100w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/if-feed-y-web.jpg 1080w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/indicatic.org.pa\/fr\/oportunidades\/vacante-asistente-investigacion-ingenieria-panama-junio-2025\/\" title=\"Poste vacant : Assistant technique de recherche en ing\u00e9nierie | INDICATIC AIP\">Poste vacant : Assistant technique de recherche en ing\u00e9nierie | INDICATIC AIP<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Poste vacant ferm\u00e9<\/p><\/div>\n                    <\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-8401\" data-id=\"8401\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/indicatic.org.pa\/fr\/oportunidades\/el-indicatic-aip-busca-un-a-asistente-de-investigacion-en-ing-de-sistemas-y-computacion\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/Vacante-asistente-de-investigacion-600x600.jpg\" class=\"attachment-medium size-medium wp-image-10443\" alt=\"Vacante asistente de investigacion\" srcset=\"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/Vacante-asistente-de-investigacion-600x600.jpg 600w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/Vacante-asistente-de-investigacion-1024x1024.jpg 1024w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/Vacante-asistente-de-investigacion-150x150.jpg 150w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/Vacante-asistente-de-investigacion-768x768.jpg 768w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/Vacante-asistente-de-investigacion-12x12.jpg 12w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/Vacante-asistente-de-investigacion-700x700.jpg 700w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/Vacante-asistente-de-investigacion-100x100.jpg 100w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/Vacante-asistente-de-investigacion.jpg 1080w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/indicatic.org.pa\/fr\/oportunidades\/el-indicatic-aip-busca-un-a-asistente-de-investigacion-en-ing-de-sistemas-y-computacion\/\" title=\"INDICATIC L&#039;AIP recherche un assistant de recherche dans le domaine de l&#039;ing\u00e9nierie informatique et des syst\u00e8mes.\">INDICATIC L'AIP recherche un assistant de recherche dans le domaine de l'ing\u00e9nierie informatique et des syst\u00e8mes.<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Poste vacant ferm\u00e9<\/p><\/div>\n                    <\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-8296\" data-id=\"8296\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/indicatic.org.pa\/fr\/oportunidades\/el-indicatic-aip-busca-investigadores-con-grado-phd-en-computer-science-o-grados-afines\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2024\/04\/Vacante-investigadores-600x600.webp\" class=\"attachment-medium size-medium wp-image-10585\" alt=\"Vacante investigadores\" srcset=\"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2024\/04\/Vacante-investigadores-600x600.webp 600w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2024\/04\/Vacante-investigadores-150x150.webp 150w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2024\/04\/Vacante-investigadores-768x768.webp 768w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2024\/04\/Vacante-investigadores-12x12.webp 12w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2024\/04\/Vacante-investigadores-700x700.webp 700w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2024\/04\/Vacante-investigadores-100x100.webp 100w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2024\/04\/Vacante-investigadores.webp 1000w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/indicatic.org.pa\/fr\/oportunidades\/el-indicatic-aip-busca-investigadores-con-grado-phd-en-computer-science-o-grados-afines\/\" title=\"Le PIA INDICATIC recherche des chercheurs titulaires d&#039;un doctorat en informatique ou dans un domaine connexe.\">Le PIA INDICATIC recherche des chercheurs titulaires d'un doctorat en informatique ou dans un domaine connexe.<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Poste vacant ferm\u00e9<\/p><\/div>\n                    <\/div><\/div><\/div>\n        <\/div>\n    <\/article><\/div>\n            <div class=\"clearfix\"><\/div>\n        <\/div>            <div class=\"eael-load-more-button-wrap eael-force-hide\">\n                <button class=\"eael-load-more-button\" id=\"eael-load-more-btn-1556dad\" data-widget-id=\"1556dad\" data-widget=\"1556dad\" data-page-id=\"7394\" data-template=\"{&quot;dir&quot;:&quot;lite&quot;,&quot;file_name&quot;:&quot;one.php&quot;,&quot;name&quot;:&quot;Post-Grid&quot;}\" data-class=\"Essential_Addons_Elementor\\Elements\\Post_Grid\" data-layout=\"masonry\" data-page=\"1\" data-args=\"orderby=date&amp;order=desc&amp;ignore_sticky_posts=1&amp;post_status=publish&amp;posts_per_page=4&amp;offset=0&amp;post_type=oportunidades&amp;tax_query%5B0%5D%5Btaxonomy%5D=tipo_oportunidad&amp;tax_query%5B0%5D%5Bfield%5D=term_id&amp;tax_query%5B0%5D%5Bterms%5D%5B0%5D=47&amp;tax_query%5Brelation%5D=AND\" data-max-page=\"2\">\n                    <span class=\"eael-btn-loader button__loader\"><\/span>\n                    <span class=\"eael_load_more_text\">Cargar m\u00e1s<\/span>\n                <\/button>\n            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-6369889 e-grid e-con-boxed e-con e-parent\" data-id=\"6369889\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;shape_divider_top&quot;:&quot;opacity-tilt&quot;,&quot;shape_divider_bottom&quot;:&quot;opacity-tilt&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 2600 131.1\" preserveaspectratio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0 0L2600 0 2600 69.1 0 0z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.5\" d=\"M0 0L2600 0 2600 69.1 0 69.1z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.25\" d=\"M2600 0L0 0 0 130.1 2600 69.1z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 2600 131.1\" preserveaspectratio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0 0L2600 0 2600 69.1 0 0z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.5\" d=\"M0 0L2600 0 2600 69.1 0 69.1z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.25\" d=\"M2600 0L0 0 0 130.1 2600 69.1z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fa07d6 elementor-widget elementor-widget-video\" data-id=\"7fa07d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/VylQdjs6_Gw?si=lHig2pBUNEpyfbDh&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2350acf elementor-widget elementor-widget-video\" data-id=\"2350acf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/rLFuGnvbkck?si=cDgbs4DxWEkMFKIY&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76cf685 elementor-widget elementor-widget-video\" data-id=\"76cf685\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/2iN03Sl9EQY?si=hp8chcD0bBT1bh8r&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4973e03 elementor-widget elementor-widget-video\" data-id=\"4973e03\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/aSeCWYf-B7o&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d5de3c elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d5de3c\" data-element_type=\"section\" data-e-type=\"section\" id=\"pasantias\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b7d62d4\" data-id=\"b7d62d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d8b5b08 elementor-position-above elementor-widget__width-inherit elementor-tablet-position-left elementor-widget-tablet__width-inherit elementor-widget elementor-widget-heading\" data-id=\"d8b5b08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-wrapper\" ><div class=\"elementor-heading-wrapper-inner\"><h2 class=\"elementor-heading-title elementor-size-default\">Pasant\u00edas disponibles<\/h2><span class=\"sub-title\">Opportunit\u00e9s<\/span><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b69da3 elementor-grid-eael-col-4 elementor-grid-tablet-eael-col-2 elementor-grid-mobile-eael-col-1 elementor-widget elementor-widget-eael-post-grid\" data-id=\"7b69da3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;eael_post_grid_columns&quot;:&quot;eael-col-4&quot;,&quot;eael_post_grid_columns_tablet&quot;:&quot;eael-col-2&quot;,&quot;eael_post_grid_columns_mobile&quot;:&quot;eael-col-1&quot;}\" data-widget_type=\"eael-post-grid.default\">\n\t\t\t\t\t<div id=\"eael-post-grid-7b69da3\" class=\"eael-post-grid-container\">\n            <div class=\"eael-post-grid eael-post-appender eael-post-appender-7b69da3 eael-post-grid-style-one\" data-layout-mode=\"masonry\"><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-9458\" data-id=\"9458\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/indicatic.org.pa\/fr\/oportunidades\/estancias-academicas-2026\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2025\/11\/1080x1080-600x600.png\" class=\"attachment-medium size-medium wp-image-9492\" alt=\"s\u00e9jours acad\u00e9miques INDICATIQUE PIA 2026\" srcset=\"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2025\/11\/1080x1080-600x600.png 600w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2025\/11\/1080x1080-1024x1024.png 1024w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2025\/11\/1080x1080-150x150.png 150w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2025\/11\/1080x1080-768x768.png 768w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2025\/11\/1080x1080-12x12.png 12w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2025\/11\/1080x1080-700x700.png 700w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2025\/11\/1080x1080-100x100.png 100w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2025\/11\/1080x1080.png 1080w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/indicatic.org.pa\/fr\/oportunidades\/estancias-academicas-2026\/\" title=\"Programme de s\u00e9jours acad\u00e9miques 2026\">Programme de s\u00e9jours acad\u00e9miques 2026<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Pasant\u00eda Cerrada<\/p><\/div>\n                    <\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-8076\" data-id=\"8076\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/indicatic.org.pa\/fr\/oportunidades\/programa-indicatic-aip-utp-sure-ipro-at-illinois\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2024\/03\/portada-600x600.webp\" class=\"attachment-medium size-medium wp-image-8081\" alt=\"portada\" srcset=\"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2024\/03\/portada-600x600.webp 600w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2024\/03\/portada-1024x1024.webp 1024w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2024\/03\/portada-150x150.webp 150w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2024\/03\/portada-768x768.webp 768w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2024\/03\/portada-12x12.webp 12w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2024\/03\/portada-700x700.webp 700w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2024\/03\/portada-100x100.webp 100w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2024\/03\/portada.webp 1080w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/indicatic.org.pa\/fr\/oportunidades\/programa-indicatic-aip-utp-sure-ipro-at-illinois\/\" title=\"Programa INDICATIC AIP &#8211; UTP SURE &#8211; IPro at Illinois 2024\">Programa INDICATIC AIP &#8211; UTP SURE &#8211; IPro at Illinois 2024<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Pasant\u00eda Cerrada<\/p><\/div>\n                    <\/div><\/div><\/div>\n        <\/div>\n    <\/article><\/div>\n            <div class=\"clearfix\"><\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f9f142 elementor-section-stretched d-none elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f9f142\" data-element_type=\"section\" data-e-type=\"section\" id=\"otras-oportunidades\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-335cfe8\" data-id=\"335cfe8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c2a751b elementor-position-above elementor-widget__width-inherit elementor-tablet-position-left elementor-widget-tablet__width-inherit elementor-widget elementor-widget-heading\" data-id=\"c2a751b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-wrapper\" ><div class=\"elementor-heading-wrapper-inner\"><h2 class=\"elementor-heading-title elementor-size-default\">Otras oportunidades externas<\/h2><span class=\"sub-title\">Opportunit\u00e9s<\/span><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74b9bb0 elementor-grid-eael-col-4 elementor-grid-tablet-eael-col-2 elementor-grid-mobile-eael-col-1 elementor-widget elementor-widget-eael-post-grid\" data-id=\"74b9bb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;eael_post_grid_columns&quot;:&quot;eael-col-4&quot;,&quot;eael_post_grid_columns_tablet&quot;:&quot;eael-col-2&quot;,&quot;eael_post_grid_columns_mobile&quot;:&quot;eael-col-1&quot;}\" data-widget_type=\"eael-post-grid.default\">\n\t\t\t\t\t<div id=\"eael-post-grid-74b9bb0\" class=\"eael-post-grid-container\">\n            <div class=\"eael-post-grid eael-post-appender eael-post-appender-74b9bb0 eael-post-grid-style-one\" data-layout-mode=\"masonry\"><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-10597\" data-id=\"10597\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/indicatic.org.pa\/fr\/oportunidades\/vacante-asistente-tecnico-en-tecnologia-indicatic-aip\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/08\/Vacante_agosto2026-1080x1080-X-LK-3-600x600.png\" class=\"attachment-medium size-medium wp-image-10608\" alt=\"Vacante Asistente de Proyecto de Investigaci\u00f3n Panam\u00e1\" srcset=\"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/08\/Vacante_agosto2026-1080x1080-X-LK-3-600x600.png 600w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/08\/Vacante_agosto2026-1080x1080-X-LK-3-1024x1024.png 1024w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/08\/Vacante_agosto2026-1080x1080-X-LK-3-150x150.png 150w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/08\/Vacante_agosto2026-1080x1080-X-LK-3-768x768.png 768w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/08\/Vacante_agosto2026-1080x1080-X-LK-3-12x12.png 12w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/08\/Vacante_agosto2026-1080x1080-X-LK-3-700x700.png 700w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/08\/Vacante_agosto2026-1080x1080-X-LK-3-100x100.png 100w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/08\/Vacante_agosto2026-1080x1080-X-LK-3.png 1080w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/indicatic.org.pa\/fr\/oportunidades\/vacante-asistente-tecnico-en-tecnologia-indicatic-aip\/\" title=\"Vacante: Asistente de Proyecto de Investigaci\u00f3n | INDICATIC AIP\">Vacante: Asistente de Proyecto de Investigaci\u00f3n | INDICATIC AIP<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Poste vacant<\/p><\/div>\n                    <\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-8916\" data-id=\"8916\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/indicatic.org.pa\/fr\/oportunidades\/vacante-asistente-investigacion-ingenieria-panama-junio-2025\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/if-feed-y-web-600x600.jpg\" class=\"attachment-medium size-medium wp-image-10442\" alt=\"if feed y web\" srcset=\"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/if-feed-y-web-600x600.jpg 600w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/if-feed-y-web-1024x1024.jpg 1024w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/if-feed-y-web-150x150.jpg 150w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/if-feed-y-web-768x768.jpg 768w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/if-feed-y-web-12x12.jpg 12w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/if-feed-y-web-700x700.jpg 700w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/if-feed-y-web-100x100.jpg 100w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/if-feed-y-web.jpg 1080w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/indicatic.org.pa\/fr\/oportunidades\/vacante-asistente-investigacion-ingenieria-panama-junio-2025\/\" title=\"Poste vacant : Assistant technique de recherche en ing\u00e9nierie | INDICATIC AIP\">Poste vacant : Assistant technique de recherche en ing\u00e9nierie | INDICATIC AIP<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Poste vacant ferm\u00e9<\/p><\/div>\n                    <\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-8401\" data-id=\"8401\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/indicatic.org.pa\/fr\/oportunidades\/el-indicatic-aip-busca-un-a-asistente-de-investigacion-en-ing-de-sistemas-y-computacion\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/Vacante-asistente-de-investigacion-600x600.jpg\" class=\"attachment-medium size-medium wp-image-10443\" alt=\"Vacante asistente de investigacion\" srcset=\"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/Vacante-asistente-de-investigacion-600x600.jpg 600w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/Vacante-asistente-de-investigacion-1024x1024.jpg 1024w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/Vacante-asistente-de-investigacion-150x150.jpg 150w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/Vacante-asistente-de-investigacion-768x768.jpg 768w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/Vacante-asistente-de-investigacion-12x12.jpg 12w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/Vacante-asistente-de-investigacion-700x700.jpg 700w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/Vacante-asistente-de-investigacion-100x100.jpg 100w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2026\/07\/Vacante-asistente-de-investigacion.jpg 1080w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/indicatic.org.pa\/fr\/oportunidades\/el-indicatic-aip-busca-un-a-asistente-de-investigacion-en-ing-de-sistemas-y-computacion\/\" title=\"INDICATIC L&#039;AIP recherche un assistant de recherche dans le domaine de l&#039;ing\u00e9nierie informatique et des syst\u00e8mes.\">INDICATIC L'AIP recherche un assistant de recherche dans le domaine de l'ing\u00e9nierie informatique et des syst\u00e8mes.<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Poste vacant ferm\u00e9<\/p><\/div>\n                    <\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-8296\" data-id=\"8296\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/indicatic.org.pa\/fr\/oportunidades\/el-indicatic-aip-busca-investigadores-con-grado-phd-en-computer-science-o-grados-afines\/\"><\/a><\/div><div class=\"eael-entry-thumbnail\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2024\/04\/Vacante-investigadores-600x600.webp\" class=\"attachment-medium size-medium wp-image-10585\" alt=\"Vacante investigadores\" srcset=\"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2024\/04\/Vacante-investigadores-600x600.webp 600w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2024\/04\/Vacante-investigadores-150x150.webp 150w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2024\/04\/Vacante-investigadores-768x768.webp 768w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2024\/04\/Vacante-investigadores-12x12.webp 12w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2024\/04\/Vacante-investigadores-700x700.webp 700w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2024\/04\/Vacante-investigadores-100x100.webp 100w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2024\/04\/Vacante-investigadores.webp 1000w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/indicatic.org.pa\/fr\/oportunidades\/el-indicatic-aip-busca-investigadores-con-grado-phd-en-computer-science-o-grados-afines\/\" title=\"Le PIA INDICATIC recherche des chercheurs titulaires d&#039;un doctorat en informatique ou dans un domaine connexe.\">Le PIA INDICATIC recherche des chercheurs titulaires d'un doctorat en informatique ou dans un domaine connexe.<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>Poste vacant ferm\u00e9<\/p><\/div>\n                    <\/div><\/div><\/div>\n        <\/div>\n    <\/article><\/div>\n            <div class=\"clearfix\"><\/div>\n        <\/div>            <div class=\"eael-load-more-button-wrap eael-force-hide\">\n                <button class=\"eael-load-more-button\" id=\"eael-load-more-btn-74b9bb0\" data-widget-id=\"74b9bb0\" data-widget=\"74b9bb0\" data-page-id=\"7394\" data-template=\"{&quot;dir&quot;:&quot;lite&quot;,&quot;file_name&quot;:&quot;one.php&quot;,&quot;name&quot;:&quot;Post-Grid&quot;}\" data-class=\"Essential_Addons_Elementor\\Elements\\Post_Grid\" data-layout=\"masonry\" data-page=\"1\" data-args=\"orderby=date&amp;order=desc&amp;ignore_sticky_posts=1&amp;post_status=publish&amp;posts_per_page=4&amp;offset=0&amp;post_type=oportunidades&amp;tax_query%5B0%5D%5Btaxonomy%5D=tipo_oportunidad&amp;tax_query%5B0%5D%5Bfield%5D=term_id&amp;tax_query%5B0%5D%5Bterms%5D%5B0%5D=47&amp;tax_query%5Brelation%5D=AND\" data-max-page=\"2\">\n                    <span class=\"eael-btn-loader button__loader\"><\/span>\n                    <span class=\"eael_load_more_text\">Cargar m\u00e1s<\/span>\n                <\/button>\n            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-c81a5d7 e-flex e-con-boxed e-con e-parent\" data-id=\"c81a5d7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a2ad61 elementor-widget elementor-widget-shortcode\" data-id=\"2a2ad61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"7432\" class=\"elementor elementor-7432\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-129c9859 elementor-section-stretched elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"129c9859\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-71c6ce7e\" data-id=\"71c6ce7e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ae2782e elementor-cta--layout-image-left elementor-cta--valign-top elementor-widget__width-initial elementor-cta--skin-classic call-to-action-wrapper-transform-none elementor-button-link elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"3ae2782e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"elementor-cta\">\n\n                            <div class=\"elementor-cta__content\">\n\n            \n            \n            \n                            <h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\" data-letter=\"Tienes alguna pregunta\">\n                Avez-vous des questions ?                <\/h2>\n            \n                            <div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n                    Vous pouvez nous \u00e9crire \u00e0 l'aide de notre formulaire de contact et nous faire part de votre demande.                <\/div>\n            \n                        <div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item\">\n                <a class=\"elementor-cta__button elementor-button elementor-size-md\" href=\"\/fr\/contacto\/\">\n                                    <span class=\"elementor-button-icon elementor-align-icon-right\">\n                                <i class=\"opal-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                            <\/span>\n                                <span>Contactez-nous \u00e0 l'adresse suivante<\/span>\n                <\/a>\n                <\/div>\n                        <\/div>\n                        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-af4894c\" data-id=\"af4894c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-235a8ec elementor-cta--layout-image-left elementor-cta--valign-top elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-cta--skin-classic call-to-action-wrapper-transform-none elementor-button-link elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"235a8ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"elementor-cta\">\n\n                            <div class=\"elementor-cta__content\">\n\n            \n            \n            \n                            <h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\" data-letter=\"Trabaja con Nosotros\">\n                Travailler avec nous                <\/h2>\n            \n                            <div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n                    Rejoignez notre \u00e9quipe et d\u00e9couvrez les opportunit\u00e9s qui s'offrent \u00e0 vous chez INDICATIC AIP.                <\/div>\n            \n                        <div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item\">\n                <a class=\"elementor-cta__button elementor-button elementor-size-md\" href=\"\/fr\/opportunites\/\">\n                                    <span class=\"elementor-button-icon elementor-align-icon-right\">\n                                <i class=\"opal-icon-arrow-right\" aria-hidden=\"true\"><\/i>\n                            <\/span>\n                                <span>Voir les opportunit\u00e9s<\/span>\n                <\/a>\n                <\/div>\n                        <\/div>\n                        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Vacantes Oportunidades Vacante: Asistente T\u00e9cnico de investigaci\u00f3n en Ingenier\u00eda | INDICATIC AIP Vacante Cerrada El INDICATIC AIP, busca un (a) asistente de investigaci\u00f3n en Ing. de Sistemas y Computaci\u00f3n Vacante &hellip; <\/p>\n<p class=\"more-link-wrap\"><a href=\"https:\/\/indicatic.org.pa\/fr\/oportunidades\/el-indicatic-aip-busca-investigadores-con-grado-phd-en-computer-science-o-grados-afines\/\" class=\"more-link\"><span>Read More<span class=\"screen-reader-text\"> \u00abEl INDICATIC AIP, busca investigadores con grado Phd en Computer Science o grados afines.\u00bb<\/span><\/span><i class=\"opal-icon-arrow-right\" aria-hidden=\"true\"><\/i><\/a><\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-elementor.php","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","inline_featured_image":false,"wpupg_custom_link":[],"wpupg_custom_link_behaviour":["default"],"wpupg_custom_link_nofollow":["default"],"wpupg_custom_image":[],"wpupg_custom_image_id":[],"_thinkrank_schema_form_data":"","_thinkrank_selected_schema_type":"","_thinkrank_additional_schemas":"","_thinkrank_canonical_url":"","_thinkrank_og_title":"","_thinkrank_og_description":"","_thinkrank_og_image":"","_thinkrank_twitter_title":"","_thinkrank_twitter_description":"","_thinkrank_twitter_image":"","_thinkrank_imported_from":"","_thinkrank_focus_keywords":[],"_thinkrank_focus_keyword":"","_thinkrank_robots_meta_enabled":0,"_thinkrank_robots_meta":"","_thinkrank_advanced_robots_meta":"","_thinkrank_primary_category":0,"footnotes":""},"class_list":["post-7394","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vacantes en INDICATIC AIP | Oportunidad laboral en tecnolog\u00eda<\/title>\n<meta name=\"description\" content=\"Explora nuestras vacantes y oportunidades profesionales en tecnolog\u00eda, ciencia de datos, innovaci\u00f3n y m\u00e1s. \u00a1\u00danete al equipo de INDICATIC AIP!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/indicatic.org.pa\/fr\/opportunites\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vacantes en INDICATIC AIP | Oportunidad laboral en tecnolog\u00eda\" \/>\n<meta property=\"og:description\" content=\"Explora nuestras vacantes y oportunidades profesionales en tecnolog\u00eda, ciencia de datos, innovaci\u00f3n y m\u00e1s. \u00a1\u00danete al equipo de INDICATIC AIP!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/indicatic.org.pa\/fr\/opportunites\/\" \/>\n<meta property=\"og:site_name\" content=\"INDICATIC AIP\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/indicaticaip\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-22T21:51:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2025\/06\/if-feed-y-web.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@indicaticaip\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/indicatic.org.pa\\\/oportunidades\\\/\",\"url\":\"https:\\\/\\\/indicatic.org.pa\\\/oportunidades\\\/\",\"name\":\"Vacantes en INDICATIC AIP | Oportunidad laboral en tecnolog\u00eda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/indicatic.org.pa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/indicatic.org.pa\\\/oportunidades\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/indicatic.org.pa\\\/oportunidades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/indicatic.org.pa\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/if-feed-y-web-600x600.png\",\"datePublished\":\"2023-12-18T20:27:55+00:00\",\"dateModified\":\"2026-04-22T21:51:31+00:00\",\"description\":\"Explora nuestras vacantes y oportunidades profesionales en tecnolog\u00eda, ciencia de datos, innovaci\u00f3n y m\u00e1s. \u00a1\u00danete al equipo de INDICATIC AIP!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/indicatic.org.pa\\\/oportunidades\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/indicatic.org.pa\\\/oportunidades\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/indicatic.org.pa\\\/oportunidades\\\/#primaryimage\",\"url\":\"https:\\\/\\\/indicatic.org.pa\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/if-feed-y-web-600x600.png\",\"contentUrl\":\"https:\\\/\\\/indicatic.org.pa\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/if-feed-y-web-600x600.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/indicatic.org.pa\\\/oportunidades\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/indicatic.org.pa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oportunidades\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/indicatic.org.pa\\\/#website\",\"url\":\"https:\\\/\\\/indicatic.org.pa\\\/\",\"name\":\"INDICATIC AIP\",\"description\":\"Instituto Nacional de Investigaciones Cient\u00edficas Avanzadas en Tecnolog\u00edas de Informaci\u00f3n y Comunicaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/indicatic.org.pa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/indicatic.org.pa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/indicatic.org.pa\\\/#organization\",\"name\":\"INDICATIC AIP\",\"url\":\"https:\\\/\\\/indicatic.org.pa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/indicatic.org.pa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/indicatic.org.pa\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/LOGO-INDICATIC-AIP.png\",\"contentUrl\":\"https:\\\/\\\/indicatic.org.pa\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/LOGO-INDICATIC-AIP.png\",\"width\":1600,\"height\":427,\"caption\":\"INDICATIC AIP\"},\"image\":{\"@id\":\"https:\\\/\\\/indicatic.org.pa\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/indicaticaip\",\"https:\\\/\\\/x.com\\\/indicaticaip\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vacantes en INDICATIC AIP | Oportunidad laboral en tecnolog\u00eda","description":"Explora nuestras vacantes y oportunidades profesionales en tecnolog\u00eda, ciencia de datos, innovaci\u00f3n y m\u00e1s. \u00a1\u00danete al equipo de INDICATIC AIP!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/indicatic.org.pa\/fr\/opportunites\/","og_locale":"fr_FR","og_type":"article","og_title":"Vacantes en INDICATIC AIP | Oportunidad laboral en tecnolog\u00eda","og_description":"Explora nuestras vacantes y oportunidades profesionales en tecnolog\u00eda, ciencia de datos, innovaci\u00f3n y m\u00e1s. \u00a1\u00danete al equipo de INDICATIC AIP!","og_url":"https:\/\/indicatic.org.pa\/fr\/opportunites\/","og_site_name":"INDICATIC AIP","article_publisher":"https:\/\/www.facebook.com\/indicaticaip","article_modified_time":"2026-04-22T21:51:31+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2025\/06\/if-feed-y-web.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@indicaticaip","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/indicatic.org.pa\/oportunidades\/","url":"https:\/\/indicatic.org.pa\/oportunidades\/","name":"Vacantes en INDICATIC AIP | Oportunidad laboral en tecnolog\u00eda","isPartOf":{"@id":"https:\/\/indicatic.org.pa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/indicatic.org.pa\/oportunidades\/#primaryimage"},"image":{"@id":"https:\/\/indicatic.org.pa\/oportunidades\/#primaryimage"},"thumbnailUrl":"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2025\/06\/if-feed-y-web-600x600.png","datePublished":"2023-12-18T20:27:55+00:00","dateModified":"2026-04-22T21:51:31+00:00","description":"Explora nuestras vacantes y oportunidades profesionales en tecnolog\u00eda, ciencia de datos, innovaci\u00f3n y m\u00e1s. \u00a1\u00danete al equipo de INDICATIC AIP!","breadcrumb":{"@id":"https:\/\/indicatic.org.pa\/oportunidades\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/indicatic.org.pa\/oportunidades\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/indicatic.org.pa\/oportunidades\/#primaryimage","url":"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2025\/06\/if-feed-y-web-600x600.png","contentUrl":"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2025\/06\/if-feed-y-web-600x600.png"},{"@type":"BreadcrumbList","@id":"https:\/\/indicatic.org.pa\/oportunidades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/indicatic.org.pa\/"},{"@type":"ListItem","position":2,"name":"Oportunidades"}]},{"@type":"WebSite","@id":"https:\/\/indicatic.org.pa\/#website","url":"https:\/\/indicatic.org.pa\/","name":"INDICATIQUE AIP","description":"Institut national de recherche scientifique avanc\u00e9e sur les technologies de l'information et de la communication (NARICIC)","publisher":{"@id":"https:\/\/indicatic.org.pa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/indicatic.org.pa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/indicatic.org.pa\/#organization","name":"INDICATIQUE AIP","url":"https:\/\/indicatic.org.pa\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/indicatic.org.pa\/#\/schema\/logo\/image\/","url":"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2023\/11\/LOGO-INDICATIC-AIP.png","contentUrl":"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2023\/11\/LOGO-INDICATIC-AIP.png","width":1600,"height":427,"caption":"INDICATIC AIP"},"image":{"@id":"https:\/\/indicatic.org.pa\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/indicaticaip","https:\/\/x.com\/indicaticaip"]}]}},"_links":{"self":[{"href":"https:\/\/indicatic.org.pa\/fr\/wp-json\/wp\/v2\/pages\/7394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indicatic.org.pa\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/indicatic.org.pa\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/indicatic.org.pa\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/indicatic.org.pa\/fr\/wp-json\/wp\/v2\/comments?post=7394"}],"version-history":[{"count":5,"href":"https:\/\/indicatic.org.pa\/fr\/wp-json\/wp\/v2\/pages\/7394\/revisions"}],"predecessor-version":[{"id":10046,"href":"https:\/\/indicatic.org.pa\/fr\/wp-json\/wp\/v2\/pages\/7394\/revisions\/10046"}],"wp:attachment":[{"href":"https:\/\/indicatic.org.pa\/fr\/wp-json\/wp\/v2\/media?parent=7394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}