{"id":9458,"date":"2025-11-11T18:36:25","date_gmt":"2025-11-11T23:36:25","guid":{"rendered":"https:\/\/indicatic.org.pa\/?post_type=oportunidades&#038;p=9458"},"modified":"2026-04-22T16:36:25","modified_gmt":"2026-04-22T21:36:25","slug":"estancias-academicas-2026","status":"publish","type":"oportunidades","link":"https:\/\/indicatic.org.pa\/fr\/oportunidades\/estancias-academicas-2026\/","title":{"rendered":"Programme de s\u00e9jours acad\u00e9miques 2026"},"content":{"rendered":"<p class=\"whitespace-normal break-words\">INDICATIC AIP y SENACYT ofrecen ocho becas completas para estancias de investigaci\u00f3n de tres meses.<\/p>\n<h2 class=\"text-lg font-bold text-text-100 mt-1 -mb-1.5\">DURACI\u00d3N Y MODALIDAD<\/h2>\n<ul class=\"[&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc space-y-2.5 pl-7\">\n<li class=\"whitespace-normal break-words\"><strong>Tres meses dividos en:<\/strong> Seis semanas en Chicago + seis semanas en Panam\u00e1<\/li>\n<li class=\"whitespace-normal break-words\"><strong>Fechas Chicago:<\/strong> 1 junio &#8211; 10 julio 2026<\/li>\n<li class=\"whitespace-normal break-words\"><strong>Modalidad:<\/strong> Presencial<\/li>\n<li class=\"whitespace-normal break-words\"><strong>Visa requerida:<\/strong> J1 non-degree visiting student<\/li>\n<\/ul>\n<h2 class=\"text-lg font-bold text-text-100 mt-1 -mb-1.5\">REQUISITOS ACAD\u00c9MICOS<\/h2>\n<ul class=\"[&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc space-y-2.5 pl-7\">\n<li>Ser Paname\u00f1o(a)<\/li>\n<li class=\"whitespace-normal break-words\">Estudiantes cursando los \u00faltimos dos a\u00f1os de carrera<\/li>\n<li class=\"whitespace-normal break-words\">Carreras: Ingenier\u00eda, Tecnolog\u00eda o Ciencias<\/li>\n<li class=\"whitespace-normal break-words\">\u00cdndice acumulado: Mayor a 1.8<\/li>\n<\/ul>\n<p>Por la naturaleza de la oportunidad es importante contar con conocimiento en programaci\u00f3n, al menos Python.<\/p>\n<h2 class=\"text-lg font-bold text-text-100 mt-1 -mb-1.5\">CERTIFICACI\u00d3N DE INGL\u00c9S (puntaje m\u00ednimo requerido)<\/h2>\n<ul class=\"[&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc space-y-2.5 pl-7\">\n<li class=\"whitespace-normal break-words\">TOEFL iBT: &gt;80<\/li>\n<li class=\"whitespace-normal break-words\">IELTS: &gt;6.5<\/li>\n<li class=\"whitespace-normal break-words\">Duolingo: &gt;115<\/li>\n<li class=\"whitespace-normal break-words\">Versant UTP: &gt;58<\/li>\n<\/ul>\n<p>Se permitir\u00e1 entregar durante este primer filtro certificaciones de a\u00f1os previos, pero luego se requerir\u00e1 uno vigente o v\u00e1lido.<\/p>\n<h2 class=\"text-lg font-bold text-text-100 mt-1 -mb-1.5\">\u00c1REAS DE INVESTIGACI\u00d3N EN CHICAGO<\/h2>\n<p>Puedes ver m\u00e1s detalles sobre las \u00e1reas de investigaci\u00f3n y experiencias previas haciendo <em><a href=\"https:\/\/indicatic.org.pa\/estancias-academicas-indicatic-aip-2026-sure-ipro\/\">clic aqu\u00ed<\/a><\/em>.<\/p>\n<p class=\"whitespace-normal break-words\">Selecciona y prioriza cuatro temas:<\/p>\n<ol class=\"[&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-decimal space-y-2.5 pl-7\">\n<li class=\"whitespace-normal break-words\">AI-Ciberseguridad \/ Ciencia de Datos<\/li>\n<li class=\"whitespace-normal break-words\">Sostenibilidad (agua, reciclaje, cadena de suministro)<\/li>\n<li class=\"whitespace-normal break-words\">Ciencia de Materiales y Manufactura Avanzada<\/li>\n<li class=\"whitespace-normal break-words\">Sistemas Aut\u00f3nomos y Rob\u00f3tica<\/li>\n<\/ol>\n<h2 class=\"text-lg font-bold text-text-100 mt-1 -mb-1.5\">\u00c1REAS DE INVESTIGACI\u00d3N EN PANAM\u00c1<\/h2>\n<p class=\"font-claude-response-body whitespace-normal break-words\"><strong>Contaminaci\u00f3n Lum\u00ednica<\/strong><\/p>\n<ul class=\"[&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc space-y-2.5 pl-7\">\n<li class=\"whitespace-normal break-words\">Investiga la calidad del cielo nocturno en Panam\u00e1<\/li>\n<li class=\"whitespace-normal break-words\">Supervisor: Dr. Jos\u00e9 Robles<\/li>\n<\/ul>\n<p class=\"font-claude-response-body whitespace-normal break-words\"><strong>Tr\u00e1fico y Movilidad Urbana<\/strong><\/p>\n<ul class=\"[&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc space-y-2.5 pl-7\">\n<li class=\"whitespace-normal break-words\">Desarrolla modelos para simular y mejorar el flujo vehicular<\/li>\n<li class=\"whitespace-normal break-words\">Supervisor: Dr. Agust\u00edn Guerra<\/li>\n<\/ul>\n<p class=\"font-claude-response-body whitespace-normal break-words\"><strong>Balance y Movimiento Humano<\/strong><\/p>\n<ul class=\"[&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc space-y-2.5 pl-7\">\n<li class=\"whitespace-normal break-words\"><em>Opci\u00f3n A:<\/em> Ayuda a personas con discapacidad visual y adultos mayores a recuperar equilibrio y autonom\u00eda<\/li>\n<li class=\"whitespace-normal break-words\"><em>Opci\u00f3n B:<\/em> Mejora el rendimiento y previene lesiones en deportistas<\/li>\n<li class=\"whitespace-normal break-words\">Supervisora: Dra. Milagros Ja\u00e9n Vargas<\/li>\n<\/ul>\n<p><strong style=\"font-size: 1rem;\">Agricultura Inteligente<\/strong><\/p>\n<ul class=\"[&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc space-y-2.5 pl-7\">\n<li class=\"whitespace-normal break-words\">Usa tecnolog\u00eda de bajo costo para optimizar fincas agr\u00edcolas y ganaderas<\/li>\n<li class=\"whitespace-normal break-words\">Supervisor: Mgtr. Jaime Gonz\u00e1lez<\/li>\n<\/ul>\n<h2 class=\"text-lg font-bold text-text-100 mt-1 -mb-1.5\">COBERTURA DE LA BECA<\/h2>\n<ul>\n<li class=\"whitespace-pre-wrap break-words\">\u00a0Matr\u00edcula del programa<\/li>\n<li class=\"whitespace-pre-wrap break-words\">Estad\u00eda y alimentaci\u00f3n en Chicago<\/li>\n<li class=\"whitespace-pre-wrap break-words\">Pasajes a\u00e9reos<\/li>\n<li class=\"whitespace-pre-wrap break-words\">Vi\u00e1ticos parciales<\/li>\n<li class=\"whitespace-pre-wrap break-words\">Apoyo en tr\u00e1mites y costos de visado<\/li>\n<li class=\"whitespace-pre-wrap break-words\">Seguro de salud<\/li>\n<\/ul>\n<h2 class=\"text-lg font-bold text-text-100 mt-1 -mb-1.5\">DOCUMENTOS REQUERIDOS (Consolidados en un solo PDF)<\/h2>\n<p>Los documentos pueden ser enviados en espa\u00f1ol, durante el primer filtro.<\/p>\n<ul class=\"[&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-decimal space-y-2.5 pl-7\">\n<li class=\"whitespace-normal break-words\">Curr\u00edculum Vitae<\/li>\n<li class=\"whitespace-normal break-words\">Carta Motivacional<\/li>\n<li class=\"whitespace-normal break-words\">Cr\u00e9ditos Acad\u00e9micos (No deben ser oficiales, pueden descargar los de su web de notas, pero es posible que se deba actualizar m\u00e1s adelante en el proceso)<\/li>\n<li class=\"whitespace-normal break-words\">Carta de Recomendaci\u00f3n<\/li>\n<li class=\"whitespace-normal break-words\">Certificaci\u00f3n de Ingl\u00e9s (Puede ser de a\u00f1os anteriores, pero es posible que se deba actualizar m\u00e1s adelante en el proceso por una vigente)<\/li>\n<li class=\"whitespace-normal break-words\">Copia de C\u00e9dula<\/li>\n<\/ul>\n<p><strong>Herramienta gratuita para combinar PDFs:<\/strong> <a class=\"underline\" href=\"https:\/\/www.ilovepdf.com\/\">https:\/\/www.ilovepdf.com\/<\/a><\/p>\n<h2 class=\"text-lg font-bold text-text-100 mt-1 -mb-1.5\">FECHA L\u00cdMITE<\/h2>\n<p class=\"whitespace-normal break-words\"><strong>31 de enero de 2026<\/strong><\/p>\n<p class=\"whitespace-normal break-words\"><strong>Aplicaci\u00f3n: <\/strong>https:\/\/forms.gle\/zE4dmLsf25damfhV8<\/p>\n<p><a href=\"https:\/\/indicatic.org.pa\/oportunidades\/convocatoria-estancias-academicas-2026\/adobe-express-qr-code-2\/\" rel=\"attachment wp-att-9460\"><img decoding=\"async\" class=\"alignnone wp-image-9460 size-thumbnail\" title=\"adobe-express-qr-code (2)\" src=\"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2025\/11\/adobe-express-qr-code-2-150x150.png\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2025\/11\/adobe-express-qr-code-2-150x150.png 150w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2025\/11\/adobe-express-qr-code-2-12x12.png 12w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2025\/11\/adobe-express-qr-code-2-100x100.png 100w, https:\/\/indicatic.org.pa\/wp-content\/uploads\/2025\/11\/adobe-express-qr-code-2.png 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><\/p>\n<p>Puedes leer m\u00e1s detalles sobre esta oportunidad y similares <em><a href=\"https:\/\/indicatic.org.pa\/estancias-academicas-indicatic-aip-2026-sure-ipro\/\">aqu\u00ed<\/a><\/em><\/p>\n<p>\u00a1Tomas las riendas de tu futuro!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pasant\u00eda Cerrada<\/p>","protected":false},"author":3,"featured_media":9492,"menu_order":0,"template":"","format":"standard","tipo_oportunidad":[54],"class_list":["post-9458","oportunidades","type-oportunidades","status-publish","format-standard","has-post-thumbnail","hentry","tipo_oportunidad-pasantias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estancias Acad\u00e9micas 2026<\/title>\n<meta name=\"description\" content=\"Convocatoria oficial dar\u00e1 8 becas completas para estancias acad\u00e9micas en Illinois Tech y Panam\u00e1. Requisitos y fechas. Cierre: 31 enero.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/indicatic.org.pa\/fr\/opportunites\/estancias-academicas-2026\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estancias Acad\u00e9micas 2026\" \/>\n<meta property=\"og:description\" content=\"Convocatoria oficial dar\u00e1 8 becas completas para estancias acad\u00e9micas en Illinois Tech y Panam\u00e1. Requisitos y fechas. Cierre: 31 enero.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/indicatic.org.pa\/fr\/opportunites\/estancias-academicas-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"INDICATIC AIP\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/indicaticaip\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-22T21:36:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2025\/11\/1080x1080.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@indicaticaip\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/indicatic.org.pa\\\/oportunidades\\\/estancias-academicas-2026\\\/\",\"url\":\"https:\\\/\\\/indicatic.org.pa\\\/oportunidades\\\/estancias-academicas-2026\\\/\",\"name\":\"Estancias Acad\u00e9micas 2026\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/indicatic.org.pa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/indicatic.org.pa\\\/oportunidades\\\/estancias-academicas-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/indicatic.org.pa\\\/oportunidades\\\/estancias-academicas-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/indicatic.org.pa\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/1080x1080.png\",\"datePublished\":\"2025-11-11T23:36:25+00:00\",\"dateModified\":\"2026-04-22T21:36:25+00:00\",\"description\":\"Convocatoria oficial dar\u00e1 8 becas completas para estancias acad\u00e9micas en Illinois Tech y Panam\u00e1. Requisitos y fechas. Cierre: 31 enero.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/indicatic.org.pa\\\/oportunidades\\\/estancias-academicas-2026\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/indicatic.org.pa\\\/oportunidades\\\/estancias-academicas-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/indicatic.org.pa\\\/oportunidades\\\/estancias-academicas-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/indicatic.org.pa\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/1080x1080.png\",\"contentUrl\":\"https:\\\/\\\/indicatic.org.pa\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/1080x1080.png\",\"width\":1080,\"height\":1080,\"caption\":\"estancias acad\u00e9micas INDICATIC AIP 2026\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/indicatic.org.pa\\\/oportunidades\\\/estancias-academicas-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/indicatic.org.pa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programa de Estancias Acad\u00e9micas 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/indicatic.org.pa\\\/#website\",\"url\":\"https:\\\/\\\/indicatic.org.pa\\\/\",\"name\":\"INDICATIC AIP\",\"description\":\"Instituto Nacional de Investigaciones Cient\u00edficas Avanzadas en Tecnolog\u00edas de Informaci\u00f3n y Comunicaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/indicatic.org.pa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/indicatic.org.pa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/indicatic.org.pa\\\/#organization\",\"name\":\"INDICATIC AIP\",\"url\":\"https:\\\/\\\/indicatic.org.pa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/indicatic.org.pa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/indicatic.org.pa\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/LOGO-INDICATIC-AIP.png\",\"contentUrl\":\"https:\\\/\\\/indicatic.org.pa\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/LOGO-INDICATIC-AIP.png\",\"width\":1600,\"height\":427,\"caption\":\"INDICATIC AIP\"},\"image\":{\"@id\":\"https:\\\/\\\/indicatic.org.pa\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/indicaticaip\",\"https:\\\/\\\/x.com\\\/indicaticaip\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estancias Acad\u00e9micas 2026","description":"Convocatoria oficial dar\u00e1 8 becas completas para estancias acad\u00e9micas en Illinois Tech y Panam\u00e1. Requisitos y fechas. Cierre: 31 enero.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/indicatic.org.pa\/fr\/opportunites\/estancias-academicas-2026\/","og_locale":"fr_FR","og_type":"article","og_title":"Estancias Acad\u00e9micas 2026","og_description":"Convocatoria oficial dar\u00e1 8 becas completas para estancias acad\u00e9micas en Illinois Tech y Panam\u00e1. Requisitos y fechas. Cierre: 31 enero.","og_url":"https:\/\/indicatic.org.pa\/fr\/opportunites\/estancias-academicas-2026\/","og_site_name":"INDICATIC AIP","article_publisher":"https:\/\/www.facebook.com\/indicaticaip","article_modified_time":"2026-04-22T21:36:25+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2025\/11\/1080x1080.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@indicaticaip","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/indicatic.org.pa\/oportunidades\/estancias-academicas-2026\/","url":"https:\/\/indicatic.org.pa\/oportunidades\/estancias-academicas-2026\/","name":"Estancias Acad\u00e9micas 2026","isPartOf":{"@id":"https:\/\/indicatic.org.pa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/indicatic.org.pa\/oportunidades\/estancias-academicas-2026\/#primaryimage"},"image":{"@id":"https:\/\/indicatic.org.pa\/oportunidades\/estancias-academicas-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2025\/11\/1080x1080.png","datePublished":"2025-11-11T23:36:25+00:00","dateModified":"2026-04-22T21:36:25+00:00","description":"Convocatoria oficial dar\u00e1 8 becas completas para estancias acad\u00e9micas en Illinois Tech y Panam\u00e1. Requisitos y fechas. Cierre: 31 enero.","breadcrumb":{"@id":"https:\/\/indicatic.org.pa\/oportunidades\/estancias-academicas-2026\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/indicatic.org.pa\/oportunidades\/estancias-academicas-2026\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/indicatic.org.pa\/oportunidades\/estancias-academicas-2026\/#primaryimage","url":"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2025\/11\/1080x1080.png","contentUrl":"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2025\/11\/1080x1080.png","width":1080,"height":1080,"caption":"estancias acad\u00e9micas INDICATIC AIP 2026"},{"@type":"BreadcrumbList","@id":"https:\/\/indicatic.org.pa\/oportunidades\/estancias-academicas-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/indicatic.org.pa\/"},{"@type":"ListItem","position":2,"name":"Programa de Estancias Acad\u00e9micas 2026"}]},{"@type":"WebSite","@id":"https:\/\/indicatic.org.pa\/#website","url":"https:\/\/indicatic.org.pa\/","name":"INDICATIQUE AIP","description":"Institut national de recherche scientifique avanc\u00e9e sur les technologies de l'information et de la communication (NARICIC)","publisher":{"@id":"https:\/\/indicatic.org.pa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/indicatic.org.pa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/indicatic.org.pa\/#organization","name":"INDICATIQUE AIP","url":"https:\/\/indicatic.org.pa\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/indicatic.org.pa\/#\/schema\/logo\/image\/","url":"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2023\/11\/LOGO-INDICATIC-AIP.png","contentUrl":"https:\/\/indicatic.org.pa\/wp-content\/uploads\/2023\/11\/LOGO-INDICATIC-AIP.png","width":1600,"height":427,"caption":"INDICATIC AIP"},"image":{"@id":"https:\/\/indicatic.org.pa\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/indicaticaip","https:\/\/x.com\/indicaticaip"]}]}},"_links":{"self":[{"href":"https:\/\/indicatic.org.pa\/fr\/wp-json\/wp\/v2\/oportunidades\/9458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indicatic.org.pa\/fr\/wp-json\/wp\/v2\/oportunidades"}],"about":[{"href":"https:\/\/indicatic.org.pa\/fr\/wp-json\/wp\/v2\/types\/oportunidades"}],"author":[{"embeddable":true,"href":"https:\/\/indicatic.org.pa\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":5,"href":"https:\/\/indicatic.org.pa\/fr\/wp-json\/wp\/v2\/oportunidades\/9458\/revisions"}],"predecessor-version":[{"id":10043,"href":"https:\/\/indicatic.org.pa\/fr\/wp-json\/wp\/v2\/oportunidades\/9458\/revisions\/10043"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/indicatic.org.pa\/fr\/wp-json\/wp\/v2\/media\/9492"}],"wp:attachment":[{"href":"https:\/\/indicatic.org.pa\/fr\/wp-json\/wp\/v2\/media?parent=9458"}],"wp:term":[{"taxonomy":"tipo_oportunidad","embeddable":true,"href":"https:\/\/indicatic.org.pa\/fr\/wp-json\/wp\/v2\/tipo_oportunidad?post=9458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}